{"id":1176,"date":"2018-10-08T14:07:39","date_gmt":"2018-10-08T14:07:39","guid":{"rendered":"https:\/\/experience-valencia.com\/tapas-tour\/"},"modified":"2019-10-22T16:00:11","modified_gmt":"2019-10-22T16:00:11","slug":"tapas-tour","status":"publish","type":"page","link":"https:\/\/experience-valencia.com\/it\/rutas-por-valencia\/tapas-tour\/","title":{"rendered":"Tapas tour + Centro Storico"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1176\" class=\"elementor elementor-1176 elementor-379\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aac39fe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aac39fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec4a1f3\" data-id=\"ec4a1f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43d4dbf dce_masking-none elementor-widget elementor-widget-image\" data-id=\"43d4dbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"600\" src=\"https:\/\/experience-valencia.com\/wp-content\/uploads\/2018\/11\/tapas.jpg\" class=\"attachment-full size-full wp-image-841\" alt=\"tapas tour Valencia\" srcset=\"https:\/\/experience-valencia.com\/wp-content\/uploads\/2018\/11\/tapas.jpg 1920w, https:\/\/experience-valencia.com\/wp-content\/uploads\/2018\/11\/tapas-300x94.jpg 300w, https:\/\/experience-valencia.com\/wp-content\/uploads\/2018\/11\/tapas-768x240.jpg 768w, https:\/\/experience-valencia.com\/wp-content\/uploads\/2018\/11\/tapas-1024x320.jpg 1024w, https:\/\/experience-valencia.com\/wp-content\/uploads\/2018\/11\/tapas-700x219.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-color=\"#bcaf9c\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9aac36c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aac36c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b7cef1\" data-id=\"7b7cef1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83439bc elementor-widget elementor-widget-text-editor\" data-id=\"83439bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">TAPAS TOUR &#8211; CENTRO STORICO<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-color=\"#e8e8e8\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a7c8cd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7c8cd0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-dce-background-color=\"#ffffff\" class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a852925\" data-id=\"a852925\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8ca3310 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ca3310\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6f58369\" data-id=\"6f58369\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-491a835 visita elementor-widget elementor-widget-text-editor\" data-id=\"491a835\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>DESCRIZIONE DELLA VISITA<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0527f84\" data-id=\"0527f84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19034aa elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"19034aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5h <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-573e229\" data-id=\"573e229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fce90f6 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"fce90f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-flag\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Espa\u00f1ol, English, Italiano, Alem\u00e1n, Franc\u00e9s<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b377ce3 elementor-widget elementor-widget-text-editor\" data-id=\"b377ce3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIl modo migliore di vivere una citt\u00e0 \u00e8 attraverso il suo cibo, quello che in Spagna \u00e8 conosciuto come &#8220;tapas&#8221;. Non c&#8217;\u00e8 modo migliore di scoprire attraverso un aperitivo, i sapori autentici e deliziosi della sua gastronomia. Per Voi abbiamo progettato un percorso attraverso diversi bar della citt\u00e0 che Vi permetter\u00e0 di gustare il miglior &#8220;picoteo&#8221; di Spagna, prevedendo una tappa speciale in uno dei pi\u00f9 grandi mercati d&#8217;Europa: il Mercato Centrale, dove Vi offriranno differenti degustazioni dei nostri prodotti tipici.<br><br>\nIl tour combiner\u00e0 una passeggiata a piedi per le vie del centro storico, con 4 fermate in diversi bar o ristoranti per assaggiare le deliziose e famose tapas sempre accompagnate da una bevanda.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3da844e elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"3da844e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6461\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6461\" aria-expanded=\"false\">\u00bfQU\u00c9 VAMOS A DESCUBRIR EN ESTA RUTA?<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-6462\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6462\" aria-expanded=\"false\">INFORMAZIONE UTILE<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-6461\" aria-expanded=\"false\">\u00bfQU\u00c9 VAMOS A DESCUBRIR EN ESTA RUTA?<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6461\" tabindex=\"0\" hidden=\"false\"><ul><li>Torri di Serrano<\/li><li>Basilica della Vergine Maria\/Madonna degli indifesi<\/li><li>Cattedrale (esterno),<\/li><li>Loggia della Seta (esterno)<\/li><li>Mercato Centrale (interno)<\/li><li>Comprese 4 degustazioni + 4 bibite<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-6462\" aria-expanded=\"false\">INFORMAZIONE UTILE<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6462\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-6462\" tabindex=\"0\" hidden=\"hidden\"><ul><li><strong>Durazione<\/strong>: 5h\u00a0<\/li><li><b>Lingue<\/b>: Espa\u00f1ol, Ingl\u00e9s, Italiano, Alem\u00e1n, Franc\u00e9s. (Consulta otros idiomas)<\/li><li><strong>Suggerimenti:<\/strong> Calzado c\u00f3modo y muchas ganas de disfrutar.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ced7c0 elementor-widget elementor-widget-google_maps\" data-id=\"8ced7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=VALENCIA&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"VALENCIA\"\n\t\t\t\t\taria-label=\"VALENCIA\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-80dc446\" data-id=\"80dc446\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43a5749 elementor-widget elementor-widget-text-editor\" data-id=\"43a5749\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00bfA QU\u00c9 ESPERAS PARA CONOCER VALENCIA?\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48f0051 form_portada elementor-widget elementor-widget-wp-widget-wpforms-widget\" data-id=\"48f0051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-wpforms-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-2461\"><form id=\"wpforms-form-2461\" class=\"wpforms-validate wpforms-form\" data-formid=\"2461\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/it\/wp-json\/wp\/v2\/pages\/1176\" data-token=\"5e8fd0dee532b20811d5f621ece9710b\" data-token-time=\"1778219607\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-2461-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2461-field_0\">Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2461-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Nombre\" required><\/div><div id=\"wpforms-2461-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2461-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2461-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Email\" spellcheck=\"false\" required><\/div><div id=\"wpforms-2461-field_3-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2461-field_3\">\u00bfEn qu\u00e9 servicio est\u00e1s interesado?<\/label><select id=\"wpforms-2461-field_3\" class=\"wpforms-field-large\" name=\"wpforms[fields][3]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>\u00bfEn qu\u00e9 servicio est\u00e1s interesado?<\/option><option value=\"Valencia centro hist\u00f3rico\"  class=\"choice-1 depth-1\"  >Valencia centro hist\u00f3rico<\/option><option value=\"Ciudad de las Artes y las Ciencas\"  class=\"choice-2 depth-1\"  >Ciudad de las Artes y las Ciencas<\/option><option value=\"Valencia sobre ruedas\"  class=\"choice-3 depth-1\"  >Valencia sobre ruedas<\/option><option value=\"Valencia gastron\u00f3mica\"  class=\"choice-4 depth-1\"  >Valencia gastron\u00f3mica<\/option><option value=\"Valencia alrededores\"  class=\"choice-5 depth-1\"  >Valencia alrededores<\/option><\/select><\/div><div id=\"wpforms-2461-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-2461-field_2\">Mensaje <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-2461-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Mensaje\" required><\/textarea><\/div><div id=\"wpforms-2461-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"4\"><label class=\"wpforms-field-label\">Informaci\u00f3n b\u00e1sica sobre Protecci\u00f3n de Datos <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2461-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2461-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Acepto el &lt;a href=&quot;https:\/\/experience-valencia.com\/aviso-legal\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Aviso legal&lt;\/a&gt; y la &lt;a href=&quot;https:\/\/experience-valencia.com\/politica-de-privacidad\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Pol\u00edtica de Privacidad&lt;\/a&gt;\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2461-field_4_1\">Acepto el <a href=\"https:\/\/experience-valencia.com\/aviso-legal\/\" target=\"_blank\" rel=\"noopener\">Aviso legal<\/a> y la <a href=\"https:\/\/experience-valencia.com\/politica-de-privacidad\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de Privacidad<\/a><\/label><\/li><\/ul><\/div><div id=\"wpforms-2461-field_5-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"5\"><div id=\"wpforms-2461-field_5\"><div style=\"font-size:12px; line-height: 14px;\">\r\n<strong>Responsable:<\/strong> Ana Isabel Arco Sola<br \/>\r\n<strong>Finalidad:<\/strong>  Obtenci\u00f3n de tu consentimiento para responder a las cuestiones que nos planteas y solicitarnos reserva a trav\u00e9s de nuestro formulario de contacto.<br \/>\r\n<strong>Legitimaci\u00f3n:<\/strong>  Consentimiento del interesado.<br \/>\r\n<strong>Destinatarios:<\/strong>  No se ceder\u00e1n datos a terceros, salvo obligaci\u00f3n legal.<br \/>\r\n<strong>Derechos:<\/strong>  Acceder, rectificar y suprimir los datos, as\u00ed como otros derechos, como se explica en la informaci\u00f3n adicional.<br \/>\r\n<strong>Informaci\u00f3n adicional:<\/strong>  Puedes consultar la informaci\u00f3n adicional y detallada sobre Protecci\u00f3n de Datos: https:\/\/experience-valencia.com\/politica-de-privacidad\/<\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-2461-field-hp\" class=\"wpforms-field-label\">Comment<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-2461-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2461\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/pages\/1176\"><input type=\"hidden\" name=\"url_referer\" value=\"https:\/\/experience-valencia.com\/it\/rutas-por-valencia\/tapas-tour\/\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2461\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1631e63 elementor-widget elementor-widget-text-editor\" data-id=\"1631e63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00bfQu\u00e9 opinan los que ya hicieron este tour?\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2991e4e elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"2991e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tEstuvimos en Valencia con un par de amigos y nos animamos a contratar un gu\u00eda para conocer mejor la ciudad. La verdad es que fue una gran decisi\u00f3n ya que Anabel adem\u00e1s del conocimiento de la ciudad es un encanto y transmite pasi\u00f3n, confianza y profesionalidad.\n\nSin duda recomendar\u00eda a Anabel a cualquiera que quiera disfrutar de una ciudad como Valencia.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Davidcamcas<\/span><span class=\"elementor-testimonial__title\">tripadvisor<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tProfessional and human quality. Excellent service! Totally recommended.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Javier Galisteo <\/span><span class=\"elementor-testimonial__title\">facebook<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tEstuvimos en Valencia con un par de amigos y nos animamos a contratar un gu\u00eda para conocer mejor la ciudad. La verdad es que fue una gran decisi\u00f3n ya que Anabel adem\u00e1s del conocimiento de la ciudad es un encanto y transmite pasi\u00f3n, confianza y profesionalidad.\n\nSin duda recomendar\u00eda a Anabel a cualquiera que quiera disfrutar de una ciudad como Valencia.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Davidcamcas<\/span><span class=\"elementor-testimonial__title\">tripadvisor<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u00c8 la guida ideale.Grande professionalit\u00e0, simpatia e affidabilit\u00e0. Consigliero' senz'altro ad altri gruppi di contattarla per farsi guidare nella visita di Valencia. Grazie.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Barra Mario<\/span><span class=\"elementor-testimonial__title\">facebook<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Precedente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Successivo\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a487cfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a487cfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5355ce\" data-id=\"b5355ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbe87db elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"cbe87db\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;transition_speed&quot;:0,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"zoomIn\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fcdf382 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Taller de paella en Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-ca8707e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Tapasa tour Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-a871dab swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Ruta de la chufa Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1649e11 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Tapas tour Valencia.comer en Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-977441b swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Taller de Paella en Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-027bc29 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Ruta del vino Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-063e56c swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Tapas tour Valencia. Gastronom\u00eda Valenciana\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-9414eb9 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Tapas tour Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c0bef67 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Ruta de la chufa Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d06e575 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Taller paella Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c6c0973 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Tapas tour en Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-34fdc57 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Gastronomia Valenciana Tours Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-9687ae6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Taller de Paella en Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-15deac4 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Ruta del vino Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-acb7e13 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\" aria-label=\"Ruta de la chufa Valencia\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva precedente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Prossima diapositiva\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TAPAS TOUR &#8211; CENTRO STORICO DESCRIZIONE DELLA VISITA 5h Espa\u00f1ol, English, Italiano, Alem\u00e1n, Franc\u00e9s Il modo migliore di vivere una citt\u00e0 \u00e8 attraverso il suo cibo, quello che in Spagna \u00e8 conosciuto come &#8220;tapas&#8221;. Non c&#8217;\u00e8 modo migliore di scoprire attraverso un aperitivo, i sapori autentici e deliziosi della sua gastronomia. Per Voi abbiamo progettato un percorso attraverso diversi bar della citt\u00e0 che Vi permetter\u00e0 di gustare il miglior &#8220;picoteo&#8221; di Spagna, prevedendo una tappa speciale in uno dei pi\u00f9 grandi mercati d&#8217;Europa: il Mercato Centrale, dove Vi offriranno differenti degustazioni dei nostri prodotti tipici. Il tour combiner\u00e0 una passeggiata&#8230;<\/p>\n","protected":false},"author":1,"featured_media":841,"parent":2035,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-1176","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/pages\/1176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/comments?post=1176"}],"version-history":[{"count":6,"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/pages\/1176\/revisions"}],"predecessor-version":[{"id":4046,"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/pages\/1176\/revisions\/4046"}],"up":[{"embeddable":true,"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/pages\/2035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/media\/841"}],"wp:attachment":[{"href":"https:\/\/experience-valencia.com\/it\/wp-json\/wp\/v2\/media?parent=1176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}